{"id":43,"count":1,"description":"","link":"https:\/\/www.seafoodstories.nl\/en\/tag\/corona\/","name":"corona","slug":"corona","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>corona Archives - Seafood Stories<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.seafoodstories.nl\/tag\/corona\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"corona Archives - Seafood Stories\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.seafoodstories.nl\/tag\/corona\/\" \/>\n<meta property=\"og:site_name\" content=\"Seafood Stories\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.seafoodstories.nl\\\/tag\\\/corona\\\/\",\"url\":\"https:\\\/\\\/www.seafoodstories.nl\\\/tag\\\/corona\\\/\",\"name\":\"corona Archives - Seafood Stories\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.seafoodstories.nl\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.seafoodstories.nl\\\/tag\\\/corona\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.seafoodstories.nl\\\/tag\\\/corona\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.seafoodstories.nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"corona\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.seafoodstories.nl\\\/#website\",\"url\":\"https:\\\/\\\/www.seafoodstories.nl\\\/\",\"name\":\"Seafood Stories\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.seafoodstories.nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"corona Archives - Seafood Stories","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.seafoodstories.nl\/tag\/corona\/","og_locale":"en_US","og_type":"article","og_title":"corona Archives - Seafood Stories","og_url":"https:\/\/www.seafoodstories.nl\/tag\/corona\/","og_site_name":"Seafood Stories","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.seafoodstories.nl\/tag\/corona\/","url":"https:\/\/www.seafoodstories.nl\/tag\/corona\/","name":"corona Archives - Seafood Stories","isPartOf":{"@id":"https:\/\/www.seafoodstories.nl\/#website"},"breadcrumb":{"@id":"https:\/\/www.seafoodstories.nl\/tag\/corona\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.seafoodstories.nl\/tag\/corona\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.seafoodstories.nl\/"},{"@type":"ListItem","position":2,"name":"corona"}]},{"@type":"WebSite","@id":"https:\/\/www.seafoodstories.nl\/#website","url":"https:\/\/www.seafoodstories.nl\/","name":"Seafood Stories","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.seafoodstories.nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.seafoodstories.nl\/en\/wp-json\/wp\/v2\/tags\/43","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.seafoodstories.nl\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.seafoodstories.nl\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.seafoodstories.nl\/en\/wp-json\/wp\/v2\/posts?tags=43"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}